{"id":3234,"count":1,"description":"","link":"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/","name":"Steak Buffet","slug":"steak-buffet","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Steak Buffet Archives - Singapore EverydayOnSales News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steak Buffet Archives - Singapore EverydayOnSales News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/\" \/>\n<meta property=\"og:site_name\" content=\"Singapore EverydayOnSales News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@sgeons\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/#organization\",\"name\":\"EverydayOnSales Singapore\",\"url\":\"https:\/\/sg.everydayonsales.com\/news\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/sgeverydayonsales\",\"https:\/\/www.instagram.com\/sgeverydayonsales\/\",\"https:\/\/twitter.com\/sgeons\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/sg.everydayonsales.com\/news\/wp-content\/uploads\/2019\/08\/SG-EverydayOnSales.jpg\",\"contentUrl\":\"https:\/\/sg.everydayonsales.com\/news\/wp-content\/uploads\/2019\/08\/SG-EverydayOnSales.jpg\",\"width\":400,\"height\":400,\"caption\":\"EverydayOnSales Singapore\"},\"image\":{\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/#website\",\"url\":\"https:\/\/sg.everydayonsales.com\/news\/\",\"name\":\"EverydayOnSales Singapore News\",\"description\":\"Trending news for Singapore\",\"publisher\":{\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/sg.everydayonsales.com\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/#webpage\",\"url\":\"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/\",\"name\":\"Steak Buffet Archives - Singapore EverydayOnSales News\",\"isPartOf\":{\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/\",\"url\":\"https:\/\/sg.everydayonsales.com\/news\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/sg.everydayonsales.com\/news\/tag\/steak-buffet\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/sg.everydayonsales.com\/news\/wp-json\/wp\/v2\/tags\/3234"}],"collection":[{"href":"https:\/\/sg.everydayonsales.com\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sg.everydayonsales.com\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sg.everydayonsales.com\/news\/wp-json\/wp\/v2\/posts?tags=3234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}